{"id":3587,"date":"2016-05-11T19:17:00","date_gmt":"2016-05-11T17:17:00","guid":{"rendered":"http:\/\/www.spd-werdohl.de\/spd\/?p=3587"},"modified":"2017-03-23T02:13:05","modified_gmt":"2017-03-23T00:13:05","slug":"freies-wlan-kommt","status":"publish","type":"post","link":"https:\/\/www.spd-werdohl.de\/spd\/2016\/05\/11\/freies-wlan-kommt\/","title":{"rendered":"Freies WLAN kommt"},"content":{"rendered":"<p><em><strong>Marcus Held<\/strong><\/em><em>, zust\u00e4ndiger Berichterstatter der AG Wirtschaft und Energie;<\/em><br \/>\n<em><strong>Christian Flisek<\/strong><\/em><em>, zust\u00e4ndiger Berichterstatter der AG Recht und Verbraucherschutz;<\/em><br \/>\n<em><strong>Lars Klingbeil<\/strong><\/em><em>, netzpolitischer Sprecher:<\/em><\/p>\n<p>\u201eDie Koalition im Bundestag hat sich darauf verst\u00e4ndigt, mit einer \u00c4nderung des Telemediengesetzes klarzustellen, dass WLAN-Anbieter als Accessprovider anzusehen sind und dass diese Haftungsprivilegierung beanspruchen kann und keinen weiteren Pr\u00fcfpflichten unterliegen. Damit wird endlich Rechtssicherheit f\u00fcr alle WLAN-Betreiber geschaffen und der Weg f\u00fcr freies WLAN in Deutschland freigemacht.<\/p>\n<p>Da das deutsche Recht keine Unterscheidung zwischen gewerblichen oder privaten Anbietern kennt, gilt diese Klarstellung f\u00fcr alle Betreiber, die ein freies WLAN anbieten. Die Haftungsprivilegierung f\u00fcr Accessprovider umfasst horizontal jede Form der Haftung, also sowohl straf-, verwaltungs- wie auch zivilrechtliche Haftung sowie die unmittelbare und mittelbare Haftung f\u00fcr Handlungen Dritter.<\/p>\n<p>Dar\u00fcber hinaus werden wir die Bundesregierung in einem Entschlie\u00dfungsantrag auffordern, sich auf europ\u00e4ischer Ebene f\u00fcr eine \u00dcberpr\u00fcfung einzusetzen, ob es \u2013 nicht zuletzt auch vor dem Hintergrund der Entscheidungen des EuGH und dessen Differenzierung hinsichtlich der neutralen beziehungsweise aktiven Rolle von Hostprovidern \u2013 einer \u00dcberarbeitung des regulatorischen Rahmens f\u00fcr Hostprovider bedarf, um illegalen Plattformen wirksam begegnen zu k\u00f6nnen.\u201c<\/p>\n<p>Quelle: <a href=\"http:\/\/www.spdfraktion.de\">www.spdfraktion.de<\/a><\/p>\n<p style=\"line-height: 17.6pt; background: white; vertical-align: baseline; margin: 0cm 0cm 8.0pt 0cm;\"><span style=\"font-size: 12.5pt; font-family: 'Tahoma','sans-serif'; color: #333333;\">Die SPD Werdohl hat die Hoffnung, dass dies nun auch in Werdohl dann so langsam zum Tragen kommt. Mehrmals hat die Werdohler SPD Ratsfraktion in verschiedenen Gremien das Thema Freies WLAN angesprochen. Die Bedenken der Verwaltung d\u00fcrften jetzt wohl ausger\u00e4umt sein, und das Freie WLAN w\u00e4re dann auch in Werdohl kein Fremdwort mehr.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marcus Held, zust\u00e4ndiger Berichterstatter der AG Wirtschaft und Energie; Christian Flisek, zust\u00e4ndiger Berichterstatter der AG Recht und Verbraucherschutz; Lars Klingbeil, netzpolitischer Sprecher: \u201eDie Koalition im Bundestag hat sich darauf verst\u00e4ndigt, mit einer \u00c4nderung des Telemediengesetzes klarzustellen, dass WLAN-Anbieter als Accessprovider anzusehen sind und dass diese Haftungsprivilegierung beanspruchen kann und keinen weiteren Pr\u00fcfpflichten unterliegen. Damit wird [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,11],"tags":[],"class_list":["post-3587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines","category-werdohl","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/posts\/3587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/comments?post=3587"}],"version-history":[{"count":6,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/posts\/3587\/revisions"}],"predecessor-version":[{"id":3838,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/posts\/3587\/revisions\/3838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/media\/3588"}],"wp:attachment":[{"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/media?parent=3587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/categories?post=3587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spd-werdohl.de\/spd\/wp-json\/wp\/v2\/tags?post=3587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}